{"id":260,"date":"2019-01-04T14:53:04","date_gmt":"2019-01-04T13:53:04","guid":{"rendered":"https:\/\/hotel-arcadien.com\/?page_id=260"},"modified":"2025-12-12T10:40:20","modified_gmt":"2025-12-12T09:40:20","slug":"restaurant-la-cabuche","status":"publish","type":"page","link":"https:\/\/www.hotelarcadien.com\/zh\/restaurant-la-cabuche\/","title":{"rendered":"\u9910\u5385"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row section vc_row-fluid \" style=' text-align:left;'><div class=\" full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_revslider_element wpb_content_element\">\n\t\t\t\t<p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t\t<sr7-module data-alias=\"restaurant\" data-id=\"6\" id=\"SR7_6_1\" class=\"rs-ov-hidden\" data-version=\"6.7.50\">\n\t\t\t\t\t<sr7-adjuster><\/sr7-adjuster>\n\t\t\t\t\t<sr7-content>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_6_1-5\" data-key=\"5\">\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_6_1-5-1\" class=\"sr7-layer\">RESTAURANT <\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_6_1-5-2\" class=\"sr7-layer\">Une carte aux bons accents de terroir Savoyard<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_6_1-5-3\" class=\"sr7-layer\">LA CABUCHE<\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t<\/sr7-content>\n\t\t\t\t<\/sr7-module>\n\t\t\t\t<script>\n\t\t\t\t\twindow.SR7 ??={};SR7.PMH ??={}; SR7.PMH[\"SR7_6_1\"] = {cn:100,state:false,fn: function() { if (_tpt!==undefined && _tpt.prepareModuleHeight !== undefined) {  _tpt.prepareModuleHeight({id:\"SR7_6_1\",el:[],type:'standard',gh:[1240],gw:[1240],vpt:['-200px'],size:{fullWidth:false, fullHeight:false},mh:'0',onh:0,onw:0,bg:{color:'',image:{src:'',size:'',position:'',repeat:''}}});   SR7.PMH[\"SR7_6_1\"].state=true;} else if(SR7.PMH[\"SR7_6_1\"].cn-->0)\tsetTimeout( SR7.PMH[\"SR7_6_1\"].fn,19);}};SR7.PMH[\"SR7_6_1\" ].fn();\n\t\t\t\t<\/script>\n<\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1553084326256\" style='background-image:url(https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/bandeau-int-resto2.jpg); text-align:center;'><div class=\" full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-480-600='184px 0% 168px 0%' data-480='184px 0% 168px 0%' data-animation='no' data-item-class='q_elements_holder_custom_232112'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_232112' style='padding:184px 8% 168px 8%'>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1><span style=\"color: #f7f7f0;\">La montagne c&rsquo;est aussi son terroir<\/span><\/h1>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small center  \" style=\"margin-top: 25px;margin-bottom: 34px;background-color: #f7f7f0;height: 1px;width: 63px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5><span style=\"color: #ffffff;\">Que ce soit avec le menu du jour ou \u00e0 la carte, l&rsquo;exp\u00e9rience montagne ne s&rsquo;arr\u00eate jamais \u00e0 l&rsquo;Arcadien H\u00f4tel &amp; Spa : une cuisine imaginative,\u00a0des plats concoct\u00e9s avec des produits locaux et avec\u00a0(plein) d&rsquo;amour par notre chef.\u00a0<\/span><\/h5>\n<h5><span style=\"color: #ffffff;\">Notre \u00e9quipe dynamique, jeune et tr\u00e8s sympa pl\u00e9biscit\u00e9e par tous les clients vous accueille tous les jours.\u00a0 <\/span><\/h5>\n<h5><span style=\"color: #ffffff;\">L&rsquo;Arcadien H\u00f4tel &amp; Spa c&rsquo;est un peu une grande famille dont vous faites partie !<\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div><div class=\"vc_empty_space\"  style=\"height: 35px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\n\t<a href=\"https:\/\/hotel-arcadien.com\/wp-content\/uploads\/2025\/12\/Carte-Restaurant-La-Cabuche-2025-12-10.pdf\" target=\"_blank\" style=\"color: #ffffff;background-color: #1f2a36\" class=\"qode-btn qode-btn-medium qode-btn-solid qode-btn-custom-hover-bg qode-btn-custom-hover-color qode-btn-default-hover\" data-hover-bg-color=\"#999087\" data-hover-color=\"#ffffff\" >\n\t    <span class=\"qode-btn-text\">La Carte<\/span>\t<\/a>\n\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1547193187439 grid_section\" style=' padding-top:50px; padding-bottom:20px; text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-1024-1280='72px 40px 0 0' data-768-1024='35px 40px 0 0' data-600-768='0px 40px 60px 0' data-480-600='0 0 60px 0' data-480='0 0 60px 0' data-animation='no' data-item-class='q_elements_holder_custom_862679'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_862679' style='padding:40px 40px 0 10px'>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #f7f7f0;\">La cuisine<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small left  \" style=\"margin-top: 28px;margin-bottom: 39px;background-color: #f7f7f0;height: 1px;width: 63px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5><span style=\"color: #f7f7f0;\">Envie de tradition Savoyarde ? Fondue, raclette, bo\u00eete chaude, tartiflette sauront r\u00e9chauffer vos coeurs! Sinon optez pour le menu du jour avec un choix de 2 entr\u00e9es \/ 2 plats \/ 2 desserts.\u00a0La demi-pension comprend le petit d\u00e9jeuner gourmand en buffet et le d\u00eener, avec choix entre le menu du jour ou une s\u00e9lection de sp\u00e9cialit\u00e9s savoyardes\u00a0<\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-600-768='0 0px 0 0px' data-480-600='0 0px 0 0px' data-480='0 0px 0 0px' data-animation='no' data-item-class='q_elements_holder_custom_465503'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_465503' style='padding:10px 0px 0px 0px'><div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/nems-reblochon-hotel-arcadien.jpg\" data-rel=\"prettyPhoto[rel-260-1907928038]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/nems-reblochon-hotel-arcadien.jpg\" class=\"attachment-full\" alt=\"\" title=\"nems-reblochon-hotel-arcadien\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/nems-reblochon-hotel-arcadien.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/nems-reblochon-hotel-arcadien-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/nems-reblochon-hotel-arcadien-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/nems-reblochon-hotel-arcadien-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/plats-3.gif\" data-rel=\"prettyPhoto[rel-260-1907928038]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/plats-3.gif\" class=\"attachment-full\" alt=\"\" title=\"restaurant h\u00f4tel arcadien les arcs\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/plat-1.gif\" data-rel=\"prettyPhoto[rel-260-1907928038]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/plat-1.gif\" class=\"attachment-full\" alt=\"\" title=\"restaurant h\u00f4tel arcadien les arcs\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/poisson-hotel-arcadien.jpg\" data-rel=\"prettyPhoto[rel-260-1907928038]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/poisson-hotel-arcadien.jpg\" class=\"attachment-full\" alt=\"\" title=\"poisson-hotel-arcadien\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/poisson-hotel-arcadien.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/poisson-hotel-arcadien-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/poisson-hotel-arcadien-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/poisson-hotel-arcadien-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/plat-arcadien.jpg\" data-rel=\"prettyPhoto[rel-260-1907928038]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/plat-arcadien.jpg\" class=\"attachment-full\" alt=\"\" title=\"plat-arcadien\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/plat-arcadien.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/plat-arcadien-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/plat-arcadien-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/plat-arcadien-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-chocolat-hotel-arcadien.jpg\" data-rel=\"prettyPhoto[rel-260-1907928038]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-chocolat-hotel-arcadien.jpg\" class=\"attachment-full\" alt=\"\" title=\"dessert-chocolat-hotel-arcadien\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-chocolat-hotel-arcadien.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-chocolat-hotel-arcadien-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-chocolat-hotel-arcadien-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-chocolat-hotel-arcadien-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-hotel-arcadien.jpg\" data-rel=\"prettyPhoto[rel-260-1907928038]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-hotel-arcadien.jpg\" class=\"attachment-full\" alt=\"\" title=\"dessert-hotel-arcadien\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-hotel-arcadien.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-hotel-arcadien-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-hotel-arcadien-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/dessert-hotel-arcadien-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style=' padding-top:20px; padding-bottom:10px; text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-1024-1280='72px 40px 0 0' data-768-1024='35px 40px 0 0' data-600-768='0px 40px 60px 0' data-480-600='0 0 60px 0' data-480='0 0 60px 0' data-animation='no' data-item-class='q_elements_holder_custom_796393'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_796393' style='padding:60px 40px 0 10px'>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #f7f7f0;\">La salle<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small left  \" style=\"margin-top: 28px;margin-bottom: 39px;background-color: #f7f7f0;height: 1px;width: 63px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5><span style=\"color: #f7f7f0;\">Un endroit privil\u00e9gi\u00e9 pour se retrouver dans un cadre \u00ab\u00a0cosy mountain\u00a0\u00bb\u00a0<\/span><\/h5>\n<h5><span style=\"color: #f7f7f0;\">La vue sur la montagne prolonge votre exp\u00e9rience des Arcs (un le\u00eftmotiv \u00e0 l&rsquo;Arcadien) et l&rsquo;atmosph\u00e8re qui r\u00e8gne au restaurant est propice au partage et aux rencontres.<\/span><\/h5>\n<p><span style=\"color: #f7f7f0;\">\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-600-768='0 0px 0 0px' data-480-600='0 0px 0 0px' data-480='0 0px 0 0px' data-animation='no' data-item-class='q_elements_holder_custom_957644'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_957644' style='padding:30px 0px 0px 0px'><div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160830.jpg\" data-rel=\"prettyPhoto[rel-260-4136102698]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160830.jpg\" class=\"attachment-full\" alt=\"\" title=\"restaurant h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160830.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160830-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160830-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160830-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_161437.jpg\" data-rel=\"prettyPhoto[rel-260-4136102698]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_161437.jpg\" class=\"attachment-full\" alt=\"\" title=\"restaurant h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_161437.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_161437-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_161437-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_161437-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160810.jpg\" data-rel=\"prettyPhoto[rel-260-4136102698]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160810.jpg\" class=\"attachment-full\" alt=\"\" title=\"restaurant h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160810.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160810-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160810-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160810-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160412.jpg\" data-rel=\"prettyPhoto[rel-260-4136102698]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160412.jpg\" class=\"attachment-full\" alt=\"\" title=\"restaurant h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160412.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160412-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160412-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_160412-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_083859.jpg\" data-rel=\"prettyPhoto[rel-260-4136102698]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_083859.jpg\" class=\"attachment-full\" alt=\"\" title=\"restaurant h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_083859.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_083859-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_083859-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_083859-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_084944.jpg\" data-rel=\"prettyPhoto[rel-260-4136102698]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_084944.jpg\" class=\"attachment-full\" alt=\"\" title=\"restaurant h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_084944.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_084944-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_084944-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_084944-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/elan.jpg\" data-rel=\"prettyPhoto[rel-260-4136102698]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/elan.jpg\" class=\"attachment-full\" alt=\"\" title=\"restaurant h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/elan.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/elan-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/elan-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/elan-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"RESTAURANT Une carte aux bons accents de terroir Savoyard LA CABUCHE La montagne c'est aussi son terroir Que ce soit avec le menu du jour ou \u00e0 la carte, l'exp\u00e9rience montagne ne s'arr\u00eate jamais \u00e0 l'Arcadien H\u00f4tel &amp; Spa : une cuisine imaginative,\u00a0des plats concoct\u00e9s...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-260","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hotelarcadien.com\/zh\/wp-json\/wp\/v2\/pages\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelarcadien.com\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelarcadien.com\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelarcadien.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelarcadien.com\/zh\/wp-json\/wp\/v2\/comments?post=260"}],"version-history":[{"count":65,"href":"https:\/\/www.hotelarcadien.com\/zh\/wp-json\/wp\/v2\/pages\/260\/revisions"}],"predecessor-version":[{"id":1187,"href":"https:\/\/www.hotelarcadien.com\/zh\/wp-json\/wp\/v2\/pages\/260\/revisions\/1187"}],"wp:attachment":[{"href":"https:\/\/www.hotelarcadien.com\/zh\/wp-json\/wp\/v2\/media?parent=260"}],"curies":[{"name":"\u53ef\u6e7f\u6027\u7c89\u5242","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}