{"id":174,"date":"2018-03-30T09:19:52","date_gmt":"2018-03-30T07:19:52","guid":{"rendered":"http:\/\/bridge198.qodeinteractive.com\/?page_id=174"},"modified":"2019-06-23T18:44:35","modified_gmt":"2019-06-23T16:44:35","slug":"activites","status":"publish","type":"page","link":"https:\/\/www.hotelarcadien.com\/ja\/activites\/","title":{"rendered":"\u6d3b\u52d5\u5185\u5bb9"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1547221673702\" style='background-color:#f7f7f0; text-align:left;'><div class=\" full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_revslider_element wpb_content_element\">\n\t\t\t\t<p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t\t<sr7-module data-alias=\"activites\" data-id=\"7\" id=\"SR7_7_1\" class=\"rs-ov-hidden\" data-version=\"6.7.50\">\n\t\t\t\t\t<sr7-adjuster><\/sr7-adjuster>\n\t\t\t\t\t<sr7-content>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_7_1-6\" data-key=\"6\">\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_7_1-6-1\" class=\"sr7-layer\">ACTIVIT\u00c9S<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_7_1-6-2\" class=\"sr7-layer\">De l'activit\u00e9 culturelle aux sports les plus extr\u00eames, il y en a pour toute la famille !\n<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_7_1-6-3\" class=\"sr7-layer\">\u00c9T\u00c9\/HIVER<\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t<\/sr7-content>\n\t\t\t\t<\/sr7-module>\n\t\t\t\t<script>\n\t\t\t\t\twindow.SR7 ??={};SR7.PMH ??={}; SR7.PMH[\"SR7_7_1\"] = {cn:100,state:false,fn: function() { if (_tpt!==undefined && _tpt.prepareModuleHeight !== undefined) {  _tpt.prepareModuleHeight({id:\"SR7_7_1\",el:[],type:'standard',gh:[1240],gw:[1240],vpt:['-200px'],size:{fullWidth:false, fullHeight:false},mh:'0',onh:0,onw:0,bg:{color:'',image:{src:'',size:'',position:'',repeat:''}}});   SR7.PMH[\"SR7_7_1\"].state=true;} else if(SR7.PMH[\"SR7_7_1\"].cn-->0)\tsetTimeout( SR7.PMH[\"SR7_7_1\"].fn,19);}};SR7.PMH[\"SR7_7_1\" ].fn();\n\t\t\t\t<\/script>\n<\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style='background-color:#1f2a36; padding-bottom:50px; text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-animation='no' data-item-class='q_elements_holder_custom_704560' style='background-color:#1f2a36;text-align:center;'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_704560' style='padding:0 11% 0 11%'><div class=\"vc_empty_space\"  style=\"height: 50px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #999087;\">Les arcs, un terrain de jeu incroyable!<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small center  \" style=\"background-color: #f7f7f0;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5 style=\"text-align: center;\"><span style=\"color: #f7f7f0;\">Et\u00e9 comme hiver il existe aux Arcs une multitude d&rsquo;activit\u00e9s qui viendront contribuer \u00e0 faire de votre s\u00e9jour une exp\u00e9rience unique. <\/span><\/h5>\n<h5 style=\"text-align: center;\"><span style=\"color: #f7f7f0;\">Notre r\u00e9gion est riche en patrimoine et les vall\u00e9es qui nous entourent nous procurent un terrain de jeu exceptionnel pour rapporter chez vous des souvenirs inoubliables.<\/span><\/h5>\n<h5><span style=\"color: #f7f7f0;\">Notre \u00e9quipe saura vous conseiller et vous aider \u00e0 organiser vos activit\u00e9s, n&rsquo;h\u00e9sitez pas \u00e0 la solliciter.<\/span><\/h5>\n<h5><span style=\"color: #f7f7f0;\">Voici ci-dessous quelques exemples d&rsquo;activit\u00e9s que vous pourrez faire. <\/span><\/h5>\n<h5><span style=\"color: #f7f7f0;\">D\u00e9sol\u00e9, pas d&rsquo;activit\u00e9s ennuyeuses chez nous! Oups&#8230;<\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  in_content_menu full_screen_section\" style='background-color:#999087; padding-bottom:60px; text-align:left;'><div class=\" full_section_inner clearfix\"><div data-vc-parallax=\"1.5\" class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill vc_general vc_parallax vc_parallax-content-moving\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768'  style='background-color:#999087'><div class='q_elements_item ' data-animation='yes' data-item-class='q_elements_holder_custom_865977' data-bottom='' data-center='' style='text-align:center;'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_865977' style='padding:0 11% 0 11%'><div class=\"qode-workflow \">\n    <span class=\"main-line\" style=\"background-color:#ffffff;\"><\/span>\n    <div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/paradiski-1.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Paradiski<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Le deuxi\u00e8me plus grand domaine au monde<\/h6>\n                                        <p class=\"text\">425 km de pistes, de 3226 \u00e0 1200 m d\u2019altitude. 2 sommets \u00e0 plus de 3000 m et 262 pistes r\u00e9parties sur une multitude de versants, le domaine offre une diversit\u00e9 de parcours in\u00e9gal\u00e9e, pour tous les niveaux.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/piscine.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Piscine ext\u00e9rieure<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Unique \u00e0 Arc 1600<\/h6>\n                                        <p class=\"text\">La piscine ext\u00e9rieure au pied de l'h\u00f4tel (ouverte l'\u00e9t\u00e9 seulement) saura vous aider \u00e0 vous rafra\u00eechir durant les belles journ\u00e9es d'\u00e9t\u00e9 par exemple apr\u00e8s une activit\u00e9 sportive.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/fete-edelweiss.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Terroir et culture<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Des \u00e9v\u00e9nements toute l&#039;ann\u00e9e<\/h6>\n                                        <p class=\"text\">Les Arcs Film Festival, f\u00eate de l'Edelweiss, salon d'agriculture de montagne, festival de musique, Ski2bike, Pierre blanche, course du coeur...<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/fat-bike.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Fat Bike<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Un VTT \u00e0 GROS pneus<\/h6>\n                                        <p class=\"text\">D\u00e9valer les pistes \u00e0 toute vitesse, \u00e0 v\u00e9lo mont\u00e9 de gros pneus \u00e0 crampons; \u00e7a vous tente? Le fat bike est fait pour vous.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/parapente2.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>parapente<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Prenez votre envol!<\/h6>\n                                        <p class=\"text\">D\u00e9couvrez autrement les vall\u00e9es et la nature exceptionnelle qui vous entourent. Et contrairement \u00e0 ce que vous pourriez penser, pas de vertige en parapente, alors laissez-vous tenter...<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/photo-wutao.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/photo-wutao.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/photo-wutao-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/photo-wutao-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/photo-wutao-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Stage Wutao<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Soyez Zen<\/h6>\n                                        <p class=\"text\">A la fronti\u00e8re entre le yoga, la danse, les arts martiaux chinois et la bio\u00e9nergie, le WUTAO permet de r\u00e9veiller l\u2019\u00e2me de notre corps. L'Arcadien accueille tous les \u00e9t\u00e9s la derni\u00e8re semaine de juillet et la premi\u00e8re d\u2019ao\u00fbt un stage de WUTAO. Contactez-nous pour plus d'informations.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/rafting.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Eaux-vives<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Une exp\u00e9rience rafra\u00eechissante<\/h6>\n                                        <p class=\"text\">Rafting, hydrospeed, canyoning...Que ce soit solo pour un max de sensations ou en \u00e9quipe pour partager les moments les plus d\u00e9lirants faites votre choix ou bien essayez-les tous!<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/kay-liedl-423158-unsplash-1.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>VTT<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">En mode balade ou sportif<\/h6>\n                                        <p class=\"text\">Le VTT est un outil parfait pour d\u00e9couvrir nos montagnes, leur flore et leur faune. Et avec les v\u00e9los \u00e9lectriques, m\u00eame les moins sportifs pourront facilement partir pour la journ\u00e9e enti\u00e8re!<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/rando.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Randonn\u00e9e p\u00e9destre<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Vous ne manquerez rien des paysages<\/h6>\n                                        <p class=\"text\">Quoi de mieux que la randonn\u00e9e entre amis ou en famille pour prendre le temps de d\u00e9couvrir la nature? Appareil photo, pique-nique, un b\u00e2ton de marche et vous voil\u00e0 partis.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/chienstraineau.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Chiens de tra\u00eeneaux<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Tout simplement magique<\/h6>\n                                        <p class=\"text\">Vous voulez offrir \u00e0 vos enfants (mais pas que) un pur moment de magie? Une balade en chiens de tra\u00eeneaux est une activit\u00e9 qu'ils n'oublieront pas de si t\u00f4t.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/scootdesneiges.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Scooter des neiges<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Sensations garanties<\/h6>\n                                        <p class=\"text\">Enfourchez la nuit tomb\u00e9e un engin incroyable et d\u00e9valez les pentes de la station \u00e0 toute allure (mais en toute s\u00e9curit\u00e9).<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/golf-1.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Golf<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">A 1800 m\u00e8tres d&#039;altitude!<\/h6>\n                                        <p class=\"text\">Un parcours 18 trous, un autre 9 trous, par 70, sur 4597 m\u00e8tres. Si les nombres ne vous impressionnent pas, l'environnement, lui oui, c'est s\u00fbr !<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/viaferrata.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Via ferrata<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Prenez de la hauteur!<\/h6>\n                                        <p class=\"text\">Beaucoup plus accessible que l'escalade, la via ferrata n'en demeure pas moins une activit\u00e9 qui offre de super sensations pour les petits comme pour les grands.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/moto.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/moto.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/moto-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/moto-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/moto-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Balades en moto<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Vous aimez les virages?<\/h6>\n                                        <p class=\"text\">Plusieurs cols magnifiques nous entourent aux Arcs. Vous pourrez passer en Italie en un tour de roue et pr\u00e9parer un superbe road book selon vos envies.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/Cyrilde_Speed_VBl_1.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Speed riding<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Entre parapente et ski<\/h6>\n                                        <p class=\"text\">Vous h\u00e9sitez entre le ski et le parapente ? Faites donc les 2 en m\u00eame temps. Votre terrain de jeu, vos r\u00e8gles. C'est \u00e7a les Arcs !<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/hero-les-arcs.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Hero les Arcs<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Avez-vous l&#039;\u00e9toffe ?<\/h6>\n                                        <p class=\"text\">Une exp\u00e9rience unique, grandeur nature, pour adultes et enfants, \u00e0 travers une multitude d\u2019activit\u00e9s outdoor sportives et ludiques sur l\u2019un des meilleurs terrains de jeu !<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/ski_joering1.gif\" class=\"attachment-full size-full\" alt=\"\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>Ski Jo\u00ebring<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Chevauchez les sommets !<\/h6>\n                                        <p class=\"text\">Encore une activit\u00e9 insolite qui fait la part belle \u00e0 la nature. Surprenant et inoubliable \u00e0 l'image des Arcs.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><div class=\"qode-workflow-item\">\n    <span class=\"line\" style=\"background-color:#1f2a36;\"><\/span>\n    <div class=\"qode-workflow-item-inner \">\n        <div class=\"qode-workflow-image center\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/mille8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/mille8.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/mille8-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/mille8-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/mille8-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>        <\/div>\n        <div class=\"qode-workflow-text\">\n            <span class=\"circle\" style=\"border-color:#ffffff;background-color:#1f2a36;\"><\/span>\n                            <h3>La piscine de Mille 8<\/h3>\n                                        <h6 class=\"qode-workflow-subtitle\">Jetez-vous \u00e0 l&#039;eau !<\/h6>\n                                        <p class=\"text\">Avec ses 3800m2 d'espaces aquatiques consacr\u00e9s au bien-\u00eatre et \u00e0 la d\u00e9tente, le centre aqualudique est situ\u00e9 au coeur d'Arc 1800.<\/p>\n                    <\/div>\n    <\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"ACTIVIT\u00c9S De l'activit\u00e9 culturelle aux sports les plus extr\u00eames, il y en a pour toute la famille ! \u00c9T\u00c9\/HIVER Les arcs, un terrain de jeu incroyable! Et\u00e9 comme hiver il existe aux Arcs une multitude d'activit\u00e9s qui viendront contribuer \u00e0 faire de votre s\u00e9jour une...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-174","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hotelarcadien.com\/ja\/wp-json\/wp\/v2\/pages\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelarcadien.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelarcadien.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelarcadien.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelarcadien.com\/ja\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":63,"href":"https:\/\/www.hotelarcadien.com\/ja\/wp-json\/wp\/v2\/pages\/174\/revisions"}],"predecessor-version":[{"id":1290,"href":"https:\/\/www.hotelarcadien.com\/ja\/wp-json\/wp\/v2\/pages\/174\/revisions\/1290"}],"wp:attachment":[{"href":"https:\/\/www.hotelarcadien.com\/ja\/wp-json\/wp\/v2\/media?parent=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}