{"id":608,"date":"2019-01-14T11:32:23","date_gmt":"2019-01-14T10:32:23","guid":{"rendered":"https:\/\/hotel-arcadien.com\/?page_id=608"},"modified":"2022-02-10T12:27:10","modified_gmt":"2022-02-10T11:27:10","slug":"spa","status":"publish","type":"page","link":"https:\/\/www.hotelarcadien.com\/it\/spa\/","title":{"rendered":"Terme"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row section vc_row-fluid \" style=' text-align:left;'><div class=\" full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_revslider_element wpb_content_element\">\n\t\t\t\t<p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t\t<sr7-module data-alias=\"spa\" data-id=\"8\" id=\"SR7_8_1\" class=\"rs-ov-hidden\" data-version=\"6.7.50\">\n\t\t\t\t\t<sr7-adjuster><\/sr7-adjuster>\n\t\t\t\t\t<sr7-content>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_8_1-7\" data-key=\"7\">\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_8_1-7-1\" class=\"sr7-layer\">SPA \n\n<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_8_1-7-2\" class=\"sr7-layer\">Et si on s'occupait un peu de VOUS?<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_8_1-7-3\" class=\"sr7-layer\">ARCADIEN\n\n<\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_8_1-21\" data-key=\"21\">\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t<\/sr7-content>\n\t\t\t\t<\/sr7-module>\n\t\t\t\t<script>\n\t\t\t\t\twindow.SR7 ??={};SR7.PMH ??={}; SR7.PMH[\"SR7_8_1\"] = {cn:100,state:false,fn: function() { if (_tpt!==undefined && _tpt.prepareModuleHeight !== undefined) {  _tpt.prepareModuleHeight({id:\"SR7_8_1\",el:[],type:'standard',gh:[1240],gw:[1240],vpt:['-200px'],size:{fullWidth:false, fullHeight:false},mh:'0',onh:0,onw:0,bg:{color:'',image:{src:'',size:'',position:'',repeat:''}}});   SR7.PMH[\"SR7_8_1\"].state=true;} else if(SR7.PMH[\"SR7_8_1\"].cn-->0)\tsetTimeout( SR7.PMH[\"SR7_8_1\"].fn,19);}};SR7.PMH[\"SR7_8_1\" ].fn();\n\t\t\t\t<\/script>\n<\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1553078967740\" style='background-image:url(https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/Fotolia_565464_M.gif); text-align:center;'><div class=\" full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-480-600='184px 0% 168px 0%' data-480='184px 0% 168px 0%' data-animation='no' data-item-class='q_elements_holder_custom_987761'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_987761' style='padding:184px 8% 168px 8%'>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1><span style=\"color: #f7f7f0;\">Chill, on prend soin de vous&#8230;<\/span><\/h1>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small center  \" style=\"margin-top: 25px;margin-bottom: 34px;background-color: #f7f7f0;height: 1px;width: 63px;\"><\/div><div class=\"vc_empty_space\"  style=\"height: 35px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\n\t<a href=\"https:\/\/www.hotel-arcadien.com\/wp-content\/uploads\/2022\/02\/carte-soins-6.pdf\" target=\"_blank\" style=\"color: #ffffff;background-color: #1f2a36\" class=\"qode-btn qode-btn-medium qode-btn-solid qode-btn-custom-hover-bg qode-btn-custom-hover-color qode-btn-default-hover\" data-hover-bg-color=\"#999087\" data-hover-color=\"#ffffff\" >\n\t    <span class=\"qode-btn-text\">CARTE DES SOINS<\/span>\t<\/a>\n\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style=' padding-top:20px; padding-bottom:20px; text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-1024-1280='72px 40px 0 0' data-768-1024='35px 40px 0 0' data-600-768='0px 40px 60px 0' data-480-600='0 0 60px 0' data-480='0 0 60px 0' data-animation='no' data-item-class='q_elements_holder_custom_139393'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_139393' style='padding:40px 40px 0 10px'>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #f7f7f0;\">Le Spa Arcadien<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small left  \" style=\"margin-top: 28px;margin-bottom: 39px;background-color: #f7f7f0;height: 1px;width: 63px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5><span style=\"color: #f7f7f0;\">Espace de bien-\u00eatre par excellence, le spa vous accueille pour de purs moments de d\u00e9tente\u00a0: sauna, jacuzzi et bain nordique en acc\u00e8s libre, s\u00e9lection irr\u00e9sistible de soins du corps prodigu\u00e9s par des mains expertes. Choisissez de vous faire pomponner\u2026jusqu\u2019\u00e0 deux heures! Essayez de ne pas vous endormir (cela arrive souvent\u00a0!) Vous pouvez r\u00e9server vos soins \u00e0 l\u2019avance, pensez-y durant la r\u00e9servation de votre chambre.<\/span><\/h5>\n<h5><\/h5>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #f7f7f0;\">\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-600-768='0 0px 0 0px' data-480-600='0 0px 0 0px' data-480='0 0px 0 0px' data-animation='no' data-item-class='q_elements_holder_custom_951328'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_951328' style='padding:30px 0px 0px 0px'><div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-1.jpeg\" data-rel=\"prettyPhoto[rel-608-1065778141]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-1.jpeg\" class=\"attachment-full\" alt=\"\" title=\"SPA-ARCADIEN\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-1.jpeg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-1-300x199.jpeg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-1-768x510.jpeg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-1-700x465.jpeg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-VOYAGE-AU-COEUR-DES-SENSATIONS-1.jpg\" data-rel=\"prettyPhoto[rel-608-1065778141]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-VOYAGE-AU-COEUR-DES-SENSATIONS-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"SPA-ARCADIEN-VOYAGE-AU-COEUR-DES-SENSATIONS\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-VOYAGE-AU-COEUR-DES-SENSATIONS-1.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-VOYAGE-AU-COEUR-DES-SENSATIONS-1-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-VOYAGE-AU-COEUR-DES-SENSATIONS-1-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-VOYAGE-AU-COEUR-DES-SENSATIONS-1-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/04\/spa-hotel-arcadien.jpg\" data-rel=\"prettyPhoto[rel-608-1065778141]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/04\/spa-hotel-arcadien.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa-hotel-arcadien\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/04\/spa-hotel-arcadien.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/04\/spa-hotel-arcadien-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/04\/spa-hotel-arcadien-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/04\/spa-hotel-arcadien-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1547555271190 grid_section\" style=' padding-top:20px; padding-bottom:20px; text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-1024-1280='72px 40px 0 0' data-768-1024='35px 40px 0 0' data-600-768='0px 40px 60px 0' data-480-600='0 0 60px 0' data-480='0 0 60px 0' data-animation='no' data-item-class='q_elements_holder_custom_513830'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_513830' style='padding:100px 40px 0 10px'>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #f7f7f0;\">L&rsquo;espace jacuzzi<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small left  \" style=\"margin-top: 28px;margin-bottom: 39px;background-color: #f7f7f0;height: 1px;width: 63px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5><span style=\"color: #f7f7f0;\">Plongez-vous dans l&rsquo;eau, d\u00e9lectez-vous des bulles chaudes qui viennent vous d\u00e9tendre, fermez les yeux et oubliez tout durant un instant.<\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-600-768='0 0px 0 0px' data-480-600='0 0px 0 0px' data-480='0 0px 0 0px' data-animation='no' data-item-class='q_elements_holder_custom_686564'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_686564' style='padding:30px 0px 0px 0px'><div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_104902.jpg\" data-rel=\"prettyPhoto[rel-608-2044714759]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_104902.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa restaurant h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_104902.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_104902-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_104902-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_104902-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113121.jpg\" data-rel=\"prettyPhoto[rel-608-2044714759]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113121.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa restaurant h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113121.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113121-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113121-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113121-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105814.jpg\" data-rel=\"prettyPhoto[rel-608-2044714759]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105814.jpg\" class=\"attachment-full\" alt=\"\" title=\"sauna h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105814.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105814-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105814-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105814-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105352.jpg\" data-rel=\"prettyPhoto[rel-608-2044714759]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105352.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105352.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105352-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105352-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_105352-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style=' padding-top:20px; padding-bottom:20px; text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-1024-1280='72px 40px 0 0' data-768-1024='35px 40px 0 0' data-600-768='0px 40px 60px 0' data-480-600='0 0 60px 0' data-480='0 0 60px 0' data-animation='no' data-item-class='q_elements_holder_custom_649560'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_649560' style='padding:100px 40px 0 10px'>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #f7f7f0;\">Bain nordique et sauna<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small left  \" style=\"margin-top: 28px;margin-bottom: 39px;background-color: #f7f7f0;height: 1px;width: 63px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5><span style=\"color: #f7f7f0;\">Quel que soit le temps ou la p\u00e9riode de l&rsquo;ann\u00e9e, vivez un moment relaxant et convivial dans notre hot tub tout en admirant la vue ou bien transpirez les toxines dans notre sauna!<\/span><\/h5>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #f7f7f0;\">\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-600-768='0 0px 0 0px' data-480-600='0 0px 0 0px' data-480='0 0px 0 0px' data-animation='no' data-item-class='q_elements_holder_custom_822689'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_822689' style='padding:30px 0px 0px 0px'><div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113915.jpg\" data-rel=\"prettyPhoto[rel-608-1110833172]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113915.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113915.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113915-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113915-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_113915-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_114058.jpg\" data-rel=\"prettyPhoto[rel-608-1110833172]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_114058.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_114058.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_114058-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_114058-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_114058-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/spa-personne.jpg\" data-rel=\"prettyPhoto[rel-608-1110833172]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/spa-personne.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/spa-personne.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/spa-personne-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/spa-personne-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/spa-personne-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1547555271190 grid_section\" style=' padding-top:20px; padding-bottom:20px; text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-1024-1280='72px 40px 0 0' data-768-1024='35px 40px 0 0' data-600-768='0px 40px 60px 0' data-480-600='0 0 60px 0' data-480='0 0 60px 0' data-animation='no' data-item-class='q_elements_holder_custom_498798'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_498798' style='padding:100px 40px 0 10px'>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #f7f7f0;\">Les soins<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small left  \" style=\"margin-top: 28px;margin-bottom: 39px;background-color: #f7f7f0;height: 1px;width: 63px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5><span style=\"color: #f7f7f0;\">Le spa vous propose des soins inspir\u00e9s des traditions ancestrales du monde entier. Ressourcez-vous au plus pr\u00e8s de la nature avec nos soins bio ZenAltitude ou embarquez pour un voyage sensoriel \u00e0 la d\u00e9couverte d\u2019horizons lointains avec nos soins La Sultane de Saba. Gommages, enveloppements, modelages, \u00e0 vous de choisir (si vous le pouvez!)<\/span><\/h5>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-600-768='0 0px 0 0px' data-480-600='0 0px 0 0px' data-480='0 0px 0 0px' data-animation='no' data-item-class='q_elements_holder_custom_940959'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_940959' style='padding:30px 0px 0px 0px'><div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/soins-spa-arcadien-1.jpg\" data-rel=\"prettyPhoto[rel-608-4222885455]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/soins-spa-arcadien-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"soins-spa-arcadien\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/soins-spa-arcadien-1.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/soins-spa-arcadien-1-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/soins-spa-arcadien-1-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/soins-spa-arcadien-1-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-HOTEL-2ARCADIEN-1.jpeg\" data-rel=\"prettyPhoto[rel-608-4222885455]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-HOTEL-2ARCADIEN-1.jpeg\" class=\"attachment-full\" alt=\"\" title=\"SPA-HOTEL-2ARCADIEN\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-HOTEL-2ARCADIEN-1.jpeg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-HOTEL-2ARCADIEN-1-300x199.jpeg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-HOTEL-2ARCADIEN-1-768x510.jpeg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-HOTEL-2ARCADIEN-1-700x465.jpeg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/christin-hume-505815-unsplash.jpg\" data-rel=\"prettyPhoto[rel-608-4222885455]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/christin-hume-505815-unsplash.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/christin-hume-505815-unsplash.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/christin-hume-505815-unsplash-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/christin-hume-505815-unsplash-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/christin-hume-505815-unsplash-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-3-1.jpg\" data-rel=\"prettyPhoto[rel-608-4222885455]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-3-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"SPA-ARCADIEN-3\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-3-1.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-3-1-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-3-1-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/06\/SPA-ARCADIEN-3-1-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/sultane-spa.jpg\" data-rel=\"prettyPhoto[rel-608-4222885455]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/sultane-spa.jpg\" class=\"attachment-full\" alt=\"\" title=\"sultane-spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/sultane-spa.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/sultane-spa-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/sultane-spa-768x509.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/03\/sultane-spa-700x464.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/max-van-den-oetelaar-646474-unsplash.jpg\" data-rel=\"prettyPhoto[rel-608-4222885455]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/max-van-den-oetelaar-646474-unsplash.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/max-van-den-oetelaar-646474-unsplash.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/max-van-den-oetelaar-646474-unsplash-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/max-van-den-oetelaar-646474-unsplash-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/max-van-den-oetelaar-646474-unsplash-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style=' padding-top:20px; padding-bottom:20px; text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-1024-1280='72px 40px 0 0' data-768-1024='35px 40px 0 0' data-600-768='0px 40px 60px 0' data-480-600='0 0 60px 0' data-480='0 0 60px 0' data-animation='no' data-item-class='q_elements_holder_custom_811901'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_811901' style='padding:100px 40px 0 10px'>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #f7f7f0;\">Salon de d\u00e9tente<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"separator  small left  \" style=\"margin-top: 28px;margin-bottom: 39px;background-color: #f7f7f0;height: 1px;width: 63px;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h5><span style=\"color: #f7f7f0;\">Vous souhaitez vous r\u00e9fugier dans notre salon zen pour lire un journal, \u00e9couter de la musique ou juste fuir vos enfants ou votre belle-m\u00e8re? Cet endroit a \u00e9t\u00e9 d\u00e9sign\u00e9 pour vous permettre tout cela!<\/span><\/h5>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #f7f7f0;\">\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item ' data-600-768='0 0px 0 0px' data-480-600='0 0px 0 0px' data-480='0 0px 0 0px' data-animation='no' data-item-class='q_elements_holder_custom_445420'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_445420' style='padding:30px 0px 0px 0px'><div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112745.jpg\" data-rel=\"prettyPhoto[rel-608-2780901950]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112745.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112745.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112745-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112745-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112745-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112336.jpg\" data-rel=\"prettyPhoto[rel-608-2780901950]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112336.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112336.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112336-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112336-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_112336-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_111827.jpg\" data-rel=\"prettyPhoto[rel-608-2780901950]\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_111827.jpg\" class=\"attachment-full\" alt=\"\" title=\"spa h\u00f4tel arcadien les arcs\" srcset=\"https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_111827.jpg 800w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_111827-300x199.jpg 300w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_111827-768x510.jpg 768w, https:\/\/www.hotelarcadien.com\/wp-content\/uploads\/2019\/01\/IMG_20190122_111827-700x465.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"SPA Et si on s'occupait un peu de VOUS? ARCADIEN Chill, on prend soin de vous... CARTE DES SOINS Le Spa Arcadien Espace de bien-\u00eatre par excellence, le spa vous accueille pour de purs moments de d\u00e9tente\u00a0: sauna, jacuzzi et bain nordique en acc\u00e8s libre,...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-608","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hotelarcadien.com\/it\/wp-json\/wp\/v2\/pages\/608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelarcadien.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelarcadien.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelarcadien.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelarcadien.com\/it\/wp-json\/wp\/v2\/comments?post=608"}],"version-history":[{"count":50,"href":"https:\/\/www.hotelarcadien.com\/it\/wp-json\/wp\/v2\/pages\/608\/revisions"}],"predecessor-version":[{"id":1420,"href":"https:\/\/www.hotelarcadien.com\/it\/wp-json\/wp\/v2\/pages\/608\/revisions\/1420"}],"wp:attachment":[{"href":"https:\/\/www.hotelarcadien.com\/it\/wp-json\/wp\/v2\/media?parent=608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}